{"id":2681,"date":"2022-07-06T16:54:22","date_gmt":"2022-07-06T19:54:22","guid":{"rendered":"https:\/\/www.mindself.com.br\/?p=2681"},"modified":"2022-07-06T16:54:22","modified_gmt":"2022-07-06T19:54:22","slug":"como-tornar-o-ambiente-de-trabalho-ainda-mais-humano","status":"publish","type":"post","link":"https:\/\/www.mindself.com.br\/en\/post\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\/","title":{"rendered":"Como tornar o ambiente de trabalho ainda mais humano"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Quando pensamos em trabalho, sabemos que se trata do antigo conceito de vender suas habilidades, sua intelig\u00eancia e seus servi\u00e7os para a empresa que te contrata. No entanto, muitas pessoas buscam em seus respectivos trabalhos algo que v\u00e1 al\u00e9m desse tipo de rela\u00e7\u00e3o e do sal\u00e1rio, e isso representa um novo desafio para quem quer contratar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Jovens profissionais t\u00eam priorizado lugares que possuam semelhan\u00e7a com seus valores e prop\u00f3sitos, pois atualmente, a hist\u00f3ria e a cultura de uma empresa s\u00e3o fatores que a gera\u00e7\u00e3o Y e Z levam em considera\u00e7\u00e3o ao se candidatar para uma vaga de emprego.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Uma <\/span><span style=\"font-weight: 400;\">pesquisa<\/span><span style=\"font-weight: 400;\"> sobre Tend\u00eancias Globais de Capital Humano 2019, da Deloitte, apontou que adaptar-se \u00e0s novidades e estabelecer um ambiente de trabalho mais humano tem criado uma vantagem competitiva na busca e reten\u00e7\u00e3o de novos talentos. Para isso, as organiza\u00e7\u00f5es precisam rever seus objetivos se quiserem avan\u00e7ar.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Por que adotar um trabalho mais humano?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">O relacionamento entre empresas e clientes tem mudado, se tornado mais pr\u00f3ximo e mais transparente. Tal mudan\u00e7a interfere diretamente no modo em que a rela\u00e7\u00e3o com os colaboradores \u00e9 conduzida. Os efeitos da transforma\u00e7\u00e3o em busca de um ambiente de trabalho mais humano influenciam tamb\u00e9m na nova gera\u00e7\u00e3o de colaboradores, que passam a ser mais cr\u00edticos e conscientes quanto \u00e0 postura das organiza\u00e7\u00f5es. Os novos profissionais n\u00e3o s\u00e3o conformados com modelos prontos e antigos, mas sim, buscam achar seu prop\u00f3sito e realiza\u00e7\u00e3o pessoal com aquilo que trabalham.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Como deixar sua empresa mais humana?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">1 \u2013 Construa locais divertidos na sua empresa: investir em um local divertido com pequenas pausas para relaxar durante o dia e com a op\u00e7\u00e3o de trabalhar a c\u00e9u aberto. Esses ambientes tamb\u00e9m s\u00e3o capazes de inspirar a criatividade, al\u00e9m de ajudar no desempenho dos funcion\u00e1rios.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">2 \u2013 Promova eventos fora do trabalho: \u00e9 uma maneira de refor\u00e7ar o esp\u00edrito de equipe, bem como ajudar na constru\u00e7\u00e3o de um bom relacionamento entre os seus colaboradores, como almo\u00e7os no final de semana ou durante a semana, mas em coletivo; happy hour e jantares \u00e0 noite; festas de confraterniza\u00e7\u00e3o; coffee breaks e palestras e atividades profissionais fora do local convencional de trabalho, entre outros.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">3 \u2013 Tenha hor\u00e1rios e espa\u00e7os flex\u00edveis: flexibilizar jornadas de trabalho \u00e9 uma forma de organiza\u00e7\u00e3o que, quando bem pensada, ajuda a aumentar a produtividade, pois permite que os funcion\u00e1rios possam operar nos hor\u00e1rios mais confort\u00e1veis para cada um.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">4 \u2013 Ofere\u00e7a cursos e workshops com as equipes: essas atividades demonstram que a sua empresa est\u00e1 investindo no crescimento profissional dos colaboradores, pois os funcion\u00e1rios tamb\u00e9m se sentem valorizados, o que contribui para tornar o ambiente mais agrad\u00e1vel e produtivo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">5 \u2013 Realize feedbacks sinceros: eles s\u00e3o importantes para que os colaboradores saibam o que as empresas esperam de seu trabalho, por isso s\u00e3o necess\u00e1rios para melhorar o desempenho e ajustar os servi\u00e7os e otimiza\u00e7\u00e3o de tarefas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">6 \u2013 Reduza a desaten\u00e7\u00e3o dos colaboradores: busque suporte tecnol\u00f3gico para estimular h\u00e1bitos saud\u00e1veis dentro da empresa. Por exemplo, o uso de softwares que otimizam a organiza\u00e7\u00e3o e o andamento de tarefas, tornando as atividades mais eficientes e completas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">7 \u2013 Elabore estrat\u00e9gias de endomarketing: \u00e9 uma iniciativa que visa melhorar os di\u00e1logos dentro da empresa, bem como atua na divulga\u00e7\u00e3o e promo\u00e7\u00e3o dos produtos e servi\u00e7os para os pr\u00f3prios colaboradores.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">8 &#8211;\u00a0 Incentive o cuidado com a sa\u00fade mental: promova atividades como reuni\u00f5es, palestras, din\u00e2micas e atividades que promovam sa\u00fade e equil\u00edbrio emocional, como por exemplo, exerc\u00edcios, rodas de conversa e a pr\u00e1tica de medita\u00e7\u00e3o no ambiente corporativo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Com base nisso, \u00e9 importante humanizar e aproximar as rela\u00e7\u00f5es dentro do ambiente corporativo, para que o espa\u00e7o de trabalho possa proporcionar bem-estar a todos os colaboradores.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Quando pensamos em trabalho, sabemos que se trata do antigo conceito de vender suas habilidades, sua intelig\u00eancia e seus servi\u00e7os para a empresa que te contrata. No entanto, muitas pessoas buscam em seus respectivos trabalhos algo que v\u00e1 al\u00e9m desse tipo de rela\u00e7\u00e3o e do sal\u00e1rio, e isso representa um novo desafio para quem quer [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":2682,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[69,70,25,27,53,68],"class_list":["post-2681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-ambiente-de-trabalho","tag-humano","tag-meditacao","tag-meditar","tag-mindself","tag-trabalho"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como tornar o ambiente de trabalho ainda mais humano - MINDSELF<\/title>\n<meta name=\"description\" content=\"Neste artigo trataremos sobre &quot;Como tornar o ambiente de trabalho ainda mais humano&quot; atrav\u00e9s da vis\u00e3o de praticantes de medita\u00e7\u00e3o e especialistas em desenvolvimento pessoal. Leia mais!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mindself.com.br\/en\/post\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como tornar o ambiente de trabalho ainda mais humano - MINDSELF\" \/>\n<meta property=\"og:description\" content=\"Neste artigo trataremos sobre &quot;Como tornar o ambiente de trabalho ainda mais humano&quot; atrav\u00e9s da vis\u00e3o de praticantes de medita\u00e7\u00e3o e especialistas em desenvolvimento pessoal. Leia mais!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mindself.com.br\/en\/post\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\/\" \/>\n<meta property=\"og:site_name\" content=\"MINDSELF\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mindselfmeditacao\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-06T19:54:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mindself.com.br\/wp-content\/uploads\/2022\/07\/oo00001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mindself\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"mindself\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/post\\\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/post\\\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\\\/\"},\"author\":{\"name\":\"mindself\",\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/en\\\/#\\\/schema\\\/person\\\/bf595ce4e6254350f15044bf4bb6e9d6\"},\"headline\":\"Como tornar o ambiente de trabalho ainda mais humano\",\"datePublished\":\"2022-07-06T19:54:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/post\\\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\\\/\"},\"wordCount\":675,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/post\\\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mindself.com.br\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/oo00001.jpg\",\"keywords\":[\"ambiente de trabalho\",\"humano\",\"medita\u00e7\u00e3o\",\"meditar\",\"mindself\",\"trabalho\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/post\\\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\\\/\",\"url\":\"https:\\\/\\\/www.mindself.com.br\\\/post\\\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\\\/\",\"name\":\"Como tornar o ambiente de trabalho ainda mais humano - MINDSELF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/post\\\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/post\\\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mindself.com.br\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/oo00001.jpg\",\"datePublished\":\"2022-07-06T19:54:22+00:00\",\"description\":\"Neste artigo trataremos sobre \\\"Como tornar o ambiente de trabalho ainda mais humano\\\" atrav\u00e9s da vis\u00e3o de praticantes de medita\u00e7\u00e3o e especialistas em desenvolvimento pessoal. Leia mais!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/post\\\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mindself.com.br\\\/post\\\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/post\\\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mindself.com.br\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/oo00001.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mindself.com.br\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/oo00001.jpg\",\"width\":1200,\"height\":638,\"caption\":\"oo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/post\\\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.mindself.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como tornar o ambiente de trabalho ainda mais humano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.mindself.com.br\\\/en\\\/\",\"name\":\"MINDSELF\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mindself.com.br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/en\\\/#organization\",\"name\":\"MINDSELF\",\"url\":\"https:\\\/\\\/www.mindself.com.br\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mindself.com.br\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/frame-164451.png\",\"contentUrl\":\"https:\\\/\\\/www.mindself.com.br\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/frame-164451.png\",\"width\":306,\"height\":42,\"caption\":\"MINDSELF\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mindselfmeditacao\",\"https:\\\/\\\/www.instagram.com\\\/mindself_meditacao\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mindself\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mindself.com.br\\\/en\\\/#\\\/schema\\\/person\\\/bf595ce4e6254350f15044bf4bb6e9d6\",\"name\":\"mindself\",\"url\":\"https:\\\/\\\/www.mindself.com.br\\\/en\\\/post\\\/author\\\/mindself\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como tornar o ambiente de trabalho ainda mais humano - MINDSELF","description":"Neste artigo trataremos sobre \"Como tornar o ambiente de trabalho ainda mais humano\" atrav\u00e9s da vis\u00e3o de praticantes de medita\u00e7\u00e3o e especialistas em desenvolvimento pessoal. Leia mais!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mindself.com.br\/en\/post\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\/","og_locale":"en_US","og_type":"article","og_title":"Como tornar o ambiente de trabalho ainda mais humano - MINDSELF","og_description":"Neste artigo trataremos sobre \"Como tornar o ambiente de trabalho ainda mais humano\" atrav\u00e9s da vis\u00e3o de praticantes de medita\u00e7\u00e3o e especialistas em desenvolvimento pessoal. Leia mais!","og_url":"https:\/\/www.mindself.com.br\/en\/post\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\/","og_site_name":"MINDSELF","article_publisher":"https:\/\/www.facebook.com\/mindselfmeditacao","article_published_time":"2022-07-06T19:54:22+00:00","og_image":[{"width":1200,"height":638,"url":"https:\/\/www.mindself.com.br\/wp-content\/uploads\/2022\/07\/oo00001.jpg","type":"image\/jpeg"}],"author":"mindself","twitter_card":"summary_large_image","twitter_misc":{"Written by":"mindself","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mindself.com.br\/post\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\/#article","isPartOf":{"@id":"https:\/\/www.mindself.com.br\/post\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\/"},"author":{"name":"mindself","@id":"https:\/\/www.mindself.com.br\/en\/#\/schema\/person\/bf595ce4e6254350f15044bf4bb6e9d6"},"headline":"Como tornar o ambiente de trabalho ainda mais humano","datePublished":"2022-07-06T19:54:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mindself.com.br\/post\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\/"},"wordCount":675,"commentCount":0,"publisher":{"@id":"https:\/\/www.mindself.com.br\/en\/#organization"},"image":{"@id":"https:\/\/www.mindself.com.br\/post\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mindself.com.br\/wp-content\/uploads\/2022\/07\/oo00001.jpg","keywords":["ambiente de trabalho","humano","medita\u00e7\u00e3o","meditar","mindself","trabalho"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.mindself.com.br\/post\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\/","url":"https:\/\/www.mindself.com.br\/post\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\/","name":"Como tornar o ambiente de trabalho ainda mais humano - MINDSELF","isPartOf":{"@id":"https:\/\/www.mindself.com.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mindself.com.br\/post\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\/#primaryimage"},"image":{"@id":"https:\/\/www.mindself.com.br\/post\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mindself.com.br\/wp-content\/uploads\/2022\/07\/oo00001.jpg","datePublished":"2022-07-06T19:54:22+00:00","description":"Neste artigo trataremos sobre \"Como tornar o ambiente de trabalho ainda mais humano\" atrav\u00e9s da vis\u00e3o de praticantes de medita\u00e7\u00e3o e especialistas em desenvolvimento pessoal. Leia mais!","breadcrumb":{"@id":"https:\/\/www.mindself.com.br\/post\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mindself.com.br\/post\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.mindself.com.br\/post\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\/#primaryimage","url":"https:\/\/www.mindself.com.br\/wp-content\/uploads\/2022\/07\/oo00001.jpg","contentUrl":"https:\/\/www.mindself.com.br\/wp-content\/uploads\/2022\/07\/oo00001.jpg","width":1200,"height":638,"caption":"oo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mindself.com.br\/post\/como-tornar-o-ambiente-de-trabalho-ainda-mais-humano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.mindself.com.br\/"},{"@type":"ListItem","position":2,"name":"Como tornar o ambiente de trabalho ainda mais humano"}]},{"@type":"WebSite","@id":"https:\/\/www.mindself.com.br\/en\/#website","url":"https:\/\/www.mindself.com.br\/en\/","name":"MINDSELF","description":"","publisher":{"@id":"https:\/\/www.mindself.com.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mindself.com.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.mindself.com.br\/en\/#organization","name":"MINDSELF","url":"https:\/\/www.mindself.com.br\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.mindself.com.br\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.mindself.com.br\/wp-content\/uploads\/2018\/09\/frame-164451.png","contentUrl":"https:\/\/www.mindself.com.br\/wp-content\/uploads\/2018\/09\/frame-164451.png","width":306,"height":42,"caption":"MINDSELF"},"image":{"@id":"https:\/\/www.mindself.com.br\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mindselfmeditacao","https:\/\/www.instagram.com\/mindself_meditacao\/","https:\/\/www.linkedin.com\/company\/mindself\/"]},{"@type":"Person","@id":"https:\/\/www.mindself.com.br\/en\/#\/schema\/person\/bf595ce4e6254350f15044bf4bb6e9d6","name":"mindself","url":"https:\/\/www.mindself.com.br\/en\/post\/author\/mindself\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mindself.com.br\/en\/wp-json\/wp\/v2\/posts\/2681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mindself.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mindself.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mindself.com.br\/en\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mindself.com.br\/en\/wp-json\/wp\/v2\/comments?post=2681"}],"version-history":[{"count":1,"href":"https:\/\/www.mindself.com.br\/en\/wp-json\/wp\/v2\/posts\/2681\/revisions"}],"predecessor-version":[{"id":2683,"href":"https:\/\/www.mindself.com.br\/en\/wp-json\/wp\/v2\/posts\/2681\/revisions\/2683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mindself.com.br\/en\/wp-json\/wp\/v2\/media\/2682"}],"wp:attachment":[{"href":"https:\/\/www.mindself.com.br\/en\/wp-json\/wp\/v2\/media?parent=2681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mindself.com.br\/en\/wp-json\/wp\/v2\/categories?post=2681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mindself.com.br\/en\/wp-json\/wp\/v2\/tags?post=2681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}